{"id":18204,"date":"2025-03-07T18:39:57","date_gmt":"2025-03-07T18:39:57","guid":{"rendered":"https:\/\/diariotiempo.com.uy\/noticias\/?p=18204"},"modified":"2025-03-07T18:39:58","modified_gmt":"2025-03-07T18:39:58","slug":"discurso-inicial","status":"publish","type":"post","link":"https:\/\/diariotiempo.com.uy\/noticias\/2025\/03\/07\/discurso-inicial\/","title":{"rendered":"DISCURSO INICIAL"},"content":{"rendered":"\n<p>El discurso inicial del nuevo presidente llam\u00f3 la atenci\u00f3n de varios analistas por lo general y hasta vago de algunos de sus conceptos. No creemos que peque de tanta vaguedad como se le ha pretendido atribuir. Se comenta que dijo mucho, sin hacer hincapi\u00e9 en ning\u00fan tema en particular. Para empezar, debe decirse que estuvo muy bien en destacar los cuarenta a\u00f1os ininterrumpidos de Democracia que lleva el Uruguay tras su \u00faltimo quebrantamiento institucional. Esa clase de manifestaciones nunca deben ser pasadas por alto y menos a\u00fan cuando se deja en claro el compromiso con la estabilidad democr\u00e1tica hacia el futuro. Y tambi\u00e9n es loable y correcto que, en esas circunstancias, en las que se transforma en el conductor de la Rep\u00fablica, recuerde sus&nbsp;or\u00edgenes. Hay tantas formas de expresarse en momentos de la inauguraci\u00f3n de un mandato presidencial, como presidentes existen. No se van a encontrar dos discursos iguales, aunque s\u00ed puede hallarse una similitud de conceptos. Por un lado, est\u00e1n aquellos mandatarios que, de arranque, trazan l\u00edneas de acciones concretas diciendo qu\u00e9 piensan hacer, cu\u00e1ndo, c\u00f3mo, a qui\u00e9nes se le va a encargar esa tarea, de d\u00f3nde se habr\u00e1n de obtener los recursos, etc. Otros, y ese es el caso de Orsi, hablan de generalidades, o sea de cosas que est\u00e1n bien para la sociedad en general, de esas que la gran mayor\u00eda de la gente acepta sin hesitaci\u00f3n, pero sin referirse a nada en concreto. Por ejemplo, cuando se refiere a la protecci\u00f3n social, especialmente a los ni\u00f1os desamparados o que nacen y viven por debajo de la l\u00ednea de pobreza, sostiene que esa es una de sus preocupaciones. Lo es de todos los uruguayos; a casi nadie le es indiferente la situaci\u00f3n en la que viven muchas de las criaturas que nacen en este pa\u00eds. Con tristeza hay que decir que el n\u00famero de las mismas ha ido en aumento y est\u00e1 bien que el presidente se sienta inquieto por ello. Por otro lado, manifest\u00f3 su convicci\u00f3n, si es que as\u00ed se le puede llamar, de buscar el \u00abcrecimiento de la econom\u00eda\u00bb, otra cosa con la que nadie, en su sano juicio, puede discrepar, as\u00ed como tampoco en que \u00abla estabilidad macroecon\u00f3mica es una pol\u00edtica de Estado\u00bb.&nbsp; Estas concepciones, as\u00ed como otras tantas que dej\u00f3 en claro al inaugurar su per\u00edodo de gobierno, resultan b\u00e1sicas para cualquier sociedad, aunque el Presidente no haya dicho c\u00f3mo piensa hacerlo. En un momento como ese, en el que est\u00e1 dirigi\u00e9ndose a la naci\u00f3n al inicio de su quinquenio a la cabeza del Poder Ejecutivo, bajo la mirada escrutadora de nacionales y extranjeros, no se le puede exigir m\u00e1s. Si as\u00ed fuera, tendr\u00eda que tomarse, al menos, cinco horas para exponer su programa y desarrollar cada uno de los temas, lo cual es pr\u00e1cticamente imposible en una ceremonia como la que se estaba viviendo. El punto es que cumpla y que sea fiel al compromiso, por su honor, que hab\u00eda hecho minutos antes. El ya Secretario de Presidencia, Alejandro S\u00e1nchez, antes de que fuese emitida la promesa, lo llam\u00f3 \u00abcompa\u00f1ero Yamand\u00fa Orsi\u00bb.&nbsp; Debi\u00f3 tenerse en cuenta que Orsi ya no era \u00abel compa\u00f1ero\u00bb, lenguaje propio de los Comit\u00e9s de Base\u00bb, sino que era el Presidente de todos los uruguayos y que su funci\u00f3n trasciende cualquier estructura partidaria. Como uruguayos, sentimos la necesidad de desearle lo mejor y, seguramente, aplaudiremos los logros que pueda alcanzar. Ojal\u00e1 que, m\u00e1s que de logros, podamos estar hablando de conquistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El discurso inicial del nuevo presidente llam\u00f3 la atenci\u00f3n de varios analistas por lo general&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-18204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-opinion"],"featured_image_urls":{"full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"thumbnail":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo-150x150.jpg",150,150,true],"medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"medium_large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"rpg_gallery_admin_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",150,93,false],"rpg_gallery_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",150,93,false],"1536x1536":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"2048x2048":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"covernews-slider-full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"covernews-slider-center":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"covernews-featured":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"covernews-medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false],"covernews-medium-square":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/06\/Master-Escribe-Cardozo.jpg",300,185,false]},"author_info":{"display_name":"diario","author_link":"https:\/\/diariotiempo.com.uy\/noticias\/author\/diario\/"},"category_info":"<a href=\"https:\/\/diariotiempo.com.uy\/noticias\/category\/opinion\/articulos-de-opinion\/\" rel=\"category tag\">Art\u00edculos de Opini\u00f3n<\/a>","tag_info":"Art\u00edculos de Opini\u00f3n","comment_count":"0","_links":{"self":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/18204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/comments?post=18204"}],"version-history":[{"count":1,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/18204\/revisions"}],"predecessor-version":[{"id":18205,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/18204\/revisions\/18205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media\/1161"}],"wp:attachment":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media?parent=18204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/categories?post=18204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/tags?post=18204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}