{"id":8702,"date":"2022-12-02T14:06:18","date_gmt":"2022-12-02T14:06:18","guid":{"rendered":"https:\/\/diariotiempo.com.uy\/noticias\/?p=8702"},"modified":"2022-12-03T14:35:15","modified_gmt":"2022-12-03T14:35:15","slug":"entregaron-mas-de-mil-contenedores-y-composteras-en-el-marco-del-programa-hogares-sustentables","status":"publish","type":"post","link":"https:\/\/diariotiempo.com.uy\/noticias\/2022\/12\/02\/entregaron-mas-de-mil-contenedores-y-composteras-en-el-marco-del-programa-hogares-sustentables\/","title":{"rendered":"Entregaron m\u00e1s de mil contenedores y composteras en el marco del programa Hogares sustentables"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"432\" src=\"https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg\" alt=\"\" class=\"wp-image-8703\" srcset=\"https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg 800w, https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-300x162.jpg 300w, https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-768x415.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>El programa Hogares Sustentables sigue adelante y este s\u00e1bado se entregaron m\u00e1s de mil contenedores y composteras para el reciclaje domiciliario en Lomas de Solymar, Ciudad de la Costa.<\/p>\n\n\n\n<p>El Intendente de Canelones, Prof. Yamand\u00fa Orsi, dijo que la actividad fue una se\u00f1al, una luz en el horizonte, \u00abque alumbra el camino que tenemos que seguir, el camino correcto\u00bb. El jerarca sostuvo que la idea no es hacer siempre lo mismo sino dar un salto en calidad, \u00abpor peque\u00f1o o grande que sea, lo importante es no quedarse quieto\u00bb. A su vez, manifest\u00f3 que \u00ablos tiempos que corren exigen innovar mucho, invertir m\u00e1s y la participaci\u00f3n y el compromiso de la gente\u00bb. Para ello, \u00abla idea es siempre estar mostrando y acercando oportunidades. Si no se les da un contenedor y se les dice que tienen que reciclar pero no tienen otro como para que lo puedan hacer, es dif\u00edcil que la gente lo haga usando infraestructura propia\u00bb, coment\u00f3. Orsi agreg\u00f3 que si los camiones de reciclaje no pasan, el programa cae, por lo que hay que concientizar, pedir que la gente participe y darles otro contenedor con la compostera como alternativa. \u00abM\u00e1s camiones, m\u00e1s tecnolog\u00eda, m\u00e1s cajas. Es un tema cultural pero fundamentalmente es de inversi\u00f3n y de compromiso institucional\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Con relaci\u00f3n al compromiso de los vecinos, inform\u00f3 que, desde hace 14 a\u00f1os, cuando se entreg\u00f3 el primer contenedor domiciliario en Las Piedras, \u00abtodos dec\u00edamos que esto es un riesgo\u00bb, por dudas sobre la adaptaci\u00f3n y el cuidado por parte de los ciudadanos; \u00abhoy es un dato que rompi\u00f3 todos las predicciones. Hasta los m\u00e1s optimistas se han sorprendido\u00bb de los buenos resultados. \u00abVale la pena, son recursos de la gente que se devuelven, pero no s\u00f3lo es bien recibido sino que se sostiene en el tiempo\u00bb, asegur\u00f3.<\/p>\n\n\n\n<p>Asimismo, el Director General de Gesti\u00f3n Ambiental de la Intendencia de Canelones, Leonardo Herou, comunic\u00f3 que se est\u00e1 iniciado una nueva etapa en la experiencia de clasificaci\u00f3n domiciliaria: \u00abA partir de ahora sumamos m\u00e1s de mil familias que reciben dos contenedores, renovamos el primero (que es para residuos no reciclables), entregamos un segundo contenedor, de tapa verde, que es para recibir el reciclaje, y sumamos una compostera. Hemos dicho varias veces que el 30 % de los residuos que generamos son reciclables, por lo que si los separamos de los comunes estamos reduciendo un 30 %; si adem\u00e1s compostamos con la fracci\u00f3n no procesada de los residuos, como ser c\u00e1scaras de papas, frutas o yerba, estamos reduciendo otro 20 % m\u00e1s. Estamos generando una inversi\u00f3n muy grande por parte de la Intendencia, son m\u00e1s de US$ 6.500.000 en equipamiento, estamos generando la log\u00edstica para que funcione y, en la medida de que logremos involucrar a los vecinos, podemos disminuir a la mitad los residuos que generamos cada d\u00eda\u00bb. Adem\u00e1s de los contenedores, se realiz\u00f3 un cambio en la flota de veh\u00edculos, se incorporan coches el\u00e9ctricos, se compr\u00f3 una barredora y contenedores grandes para residuos especiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa Hogares Sustentables sigue adelante y este s\u00e1bado se entregaron m\u00e1s de mil contenedores&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-8702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad-de-la-costa"],"featured_image_urls":{"full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"thumbnail":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-150x150.jpg",150,150,true],"medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-300x162.jpg",300,162,true],"medium_large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-768x415.jpg",640,346,true],"large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",640,346,false],"rpg_gallery_admin_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",150,81,false],"rpg_gallery_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",150,81,false],"1536x1536":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"2048x2048":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"covernews-slider-full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"covernews-slider-center":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"covernews-featured":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor.jpg",800,432,false],"covernews-medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-540x340.jpg",540,340,true],"covernews-medium-square":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2022\/12\/contenedor-400x250.jpg",400,250,true]},"author_info":{"display_name":"diario","author_link":"https:\/\/diariotiempo.com.uy\/noticias\/author\/diario\/"},"category_info":"<a href=\"https:\/\/diariotiempo.com.uy\/noticias\/category\/departamental\/ciudad-de-la-costa\/\" rel=\"category tag\">Ciudad de la Costa<\/a>","tag_info":"Ciudad de la Costa","comment_count":"0","_links":{"self":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/comments?post=8702"}],"version-history":[{"count":1,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8702\/revisions"}],"predecessor-version":[{"id":8704,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8702\/revisions\/8704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media\/8703"}],"wp:attachment":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media?parent=8702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/categories?post=8702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/tags?post=8702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}