{"id":8774,"date":"2022-12-06T13:58:07","date_gmt":"2022-12-06T13:58:07","guid":{"rendered":"https:\/\/diariotiempo.com.uy\/noticias\/?p=8774"},"modified":"2022-12-06T13:58:08","modified_gmt":"2022-12-06T13:58:08","slug":"sucesion-23","status":"publish","type":"post","link":"https:\/\/diariotiempo.com.uy\/noticias\/2022\/12\/06\/sucesion-23\/","title":{"rendered":"SUCESI\u00d3N"},"content":{"rendered":"\n<p>JUZGADO LETRADO DE PANDO DE 4\u00ba TURNO<\/p>\n\n\n\n<p>EDICTO- Por disposici\u00f3n del Sr\/a. Juez Letrado de Pando de 4\u00b0 Turno, dictada en autos:\u00bbBELL RODRIGUEZ, LIZARO.-FAMILIA.-SUCESION\u00bb IUE 2-59806\/2022, se dispuso la apertura de la sucesi\u00f3n del causante\/s LIZARO RUBEN BELL RODRIGUEZ, emplaz\u00e1ndose por edictos a herederos, acreedores y dem\u00e1s interesados para que comparezcan por el t\u00e9rmino de 30 d\u00edas, a deducir en forma sus derechos. Pando, 22 de noviembre de 2022. Firmado electronicamente por Viviana Karen Rodriguez Ruiz Actuario Adjunto .- 10 pub. de 2\/12 a 15\/12\/2022.<\/p>\n\n\n\n<p>HERENCIA YACENTE<\/p>\n\n\n\n<p>JUZGADO LETRADO<br>DE ATL\u00c1NTIDA DE 2\u00ba<br>TURNO<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez Letrado de Atl\u00e1ntida de 2\u00b0 Turno, dictada en autos: \u00abBEZMERTNEY GORDIENKO, EDITH LEONOR. HERENCIA YACENTE\u00bb IUE 526- 116\/2021, se hace saber que por auto 3346\/2022, se dispuso la apertura de la sucesi\u00f3n denunciada como yacente de la sucesi\u00f3n de EDITH LEONOR BEZMERTNEY GORDIENKO, emplaz\u00e1ndose por edictos a herederos, acreedores y dem\u00e1s interesados para que comparezcan por el t\u00e9rmino de 30 d\u00edas, a deducir en forma sus derechos (art\u00edculo 429.2 C.G.P.). Atl\u00e1ntida, 17 de noviembre de 2022 Firmado electronicamente por Andrea Prattes Diez. Actuario 30 pub. del 28\/11\/2022 al 14\/02\/2023<\/p>\n\n\n\n<p>INCAPACIDAD<\/p>\n\n\n\n<p>JUZGADO LETRADO DE PANDO DE 4\u00ba TURNO<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez Letrado de Pando de 4\u00b0 Turno en autos: \u00bb HERNANDEZ LARROSA, MARIA DE LOS ANGELES.- FAMILIA.- INCAPACIDAD.- \u00ab, IUE 176-812\/2014, se hace saber que por Resoluci\u00f3n N\u00b0 1134\/2022 de fecha 04\/04\/2022, dictada por \u00e9ste Juzgado, se removi\u00f3 del cargo de curador\/a del ya declarado incapaz M\u00aa DE LOS ANGELES HERN\u00c1NDEZ LARROSA, al\/a Sr\/a. ALBA JUDITH LARROSA MOTTA, design\u00e1ndose a tales efectos al\/a Sr\/a. RICARDO EFRA\u00cdN HERNANDEZ LARROSA, quien acept\u00f3 el cargo con fecha 04\/04\/2022 sirviendo tal providencia de suficiente discernimiento y a los efectos legales se hacen \u00e9stas publicaciones. Pando, 19 de abril de 2022. Firmado electronicamente por Viviana Karen Rodriguez Ruiz. Actuario Adjunto 10 pub. del 24\/11 al 7\/12\/2022<\/p>\n\n\n\n<p>JUZGADO LETRADO DE PANDO DE 3\u00ba TURNO<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez Letrado de Pando de 3\u00b0 Turno en autos: \u00bb GASTALDI FERREIRA, AGUSTIN. INCAPACIDAD- FAMILIA\u00bb, IUE 175-363\/2021, se hace saber que por Resoluci\u00f3n N\u00b0 3896\/2022 de fecha 15\/08\/2022, dictada por \u00e9ste Juzgado, se ha designado curador\/a definitivo\/a del ya declarado incapaz Agust\u00edn Gastaldi Ferreira, al\/a Sr\/a. Laura Andrea Ferreira Suarez, quien acept\u00f3 el cargo con fecha 15\/08\/2022 sirviendo tal providencia de suficiente discernimiento y a los efectos legales se hacen \u00e9stas publicaciones. Pando, 28 de octubre de 2022<br>Firmado electronicamente por Natalia Garcia. Actuario Adjunto 10 pub. del 24\/11 al 7\/12\/2022<\/p>\n\n\n\n<p>RATIFICACI\u00d3N<br>DE TENENCIA<\/p>\n\n\n\n<p>JUZGADO LETRADO DE TOLEDO DE 1\u00ba TURNO<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez Letrado de Toledo de 1\u00b0 Turno, dictada en autos: \u00bb BRAVO FURTADO, MIRTA -RATIFICACION DE TENENCIA-\u00bb IUE 574-402\/2021, se cita, llama y emplaza a ESTELA MAR\u00cdA BEN\u00cdTEZ por el t\u00e9rmino de 90 d\u00edas a efectos de comparecer a estar a derecho en el presente proceso, bajo apercibimiento de design\u00e1rsele Defensor de Oficio, con quien se seguir\u00e1n las actuaciones. Se deja constancia que las presentes actuaciones son patrocinadas por Defensor\u00eda de Oficio. Toledo, 10 de noviembre de 2021<br>Firmado electr\u00f3nicamente por Andrea Gissel Hern\u00e1ndez Rodriguez. Actuario Adjunto 10 pub. del 25\/11 al 8\/12\/2022<\/p>\n\n\n\n<p>JUZGADO LETRADO DE PANDO DE 3\u00ba TURNO<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez Letrado de Pando de 3\u00b0 Turno, dictada en autos: \u00bb FAGUNDEZ CARDOZO, ANGEL SEBASTIAN &#8211; RATIFICACION DE TENENCIA &#8211; FAMILIA\u00bb IUE 175-263\/2022, se cita, llama y emplaza a ERIKA ELIZABETH FAGUNDEZ CARDOZO por el t\u00e9rmino de 90 d\u00edas a efectos de comparecer a estar a derecho en el presente proceso, bajo apercibimiento de design\u00e1rsele Defensor de Oficio, con quien se seguir\u00e1n las actuaciones. Se deja constancia que las presentes actuaciones son patrocinadas por Defensor\u00eda de Oficio.<br>Pando, 20 de octubre de 2022<br>Firmado electronicamente por Lorena Falabella Valetti. Actuario Adjunto 10 pub. del 5\/12 al 16\/12\/2022<\/p>\n\n\n\n<p>PRESCRIPCI\u00d3N<br>ADQUISITIVA<\/p>\n\n\n\n<p>JUZGADO DE PAZ DEPARTAMENTAL DE ATL\u00c1NTIDA<\/p>\n\n\n\n<p>EDICTO: Por disposici\u00f3n del Sr\/a. Juez de Paz Departamental de Atl\u00e1ntida en autos: \u00bb PROTTO ROJAS, MABEL MARY PRESCRIPCION ADQUISITIVA TREINTENAL\u00bb, IUE 202-173\/2001, y seg\u00fan providencia N\u00ba 2694\/2022 de fecha 12\/10\/2022, se cita, llama y emplaza por el t\u00e9rmino de 90 d\u00edas a todos los que se consideren con derechos y especialmente al \u00faltimo titular , y sus sucesores a cualquier t\u00edtulo sobre el padr\u00f3n N\u00ba 6082 de la 18\u00aa Secci\u00f3n Judicial de Canelones, localidad catastral Parque del Plata, que seg\u00fan plano del agrimensor Carlos Curbelo, inscripto en catastro con el N\u00ba 428 del 2001, tiene una superficie de cuatrocientos noventa y dos metros cuadrados cero decimetros se deslinda as\u00ed: al noroeste 15 metros de frente a calle U1, entre calles 14 y 16, midiendo su punto extremo 20,00 metros con la esquina de la \u00faltima de las mencionadas, al noreste 33,25 metros lindando con padrones 6081 y 6080, al sureste 14,84 metrosw lindando con padr\u00f3n 6078, y al suroeste 33,25 metros lindando con padr\u00f3n 6083; bajo apercibimiento de design\u00e1rseles Defensor de Oficio. Atl\u00e1ntida, 03 de noviembre de 2022. Firmado electronicamente por Florencia Sorrondeguy Ferreira. 10 pub. del 29\/11 al 12\/12\/2022<\/p>\n\n\n\n<p>MATRIMONIO<\/p>\n\n\n\n<p>Se publican los edictos de matrimonio de las distintas oficinas de Registro Civil a los efectos de que los que supieren alg\u00fan impedimento para los matrimonios proyectados denuncien por escrito haciendo conocer las causas ante las oficinas respectivas.<\/p>\n\n\n\n<p>CIUDAD DE LA COSTA<br>OFICINA N\u00ba 14<\/p>\n\n\n\n<p>En SOLYMAR, Canelones el d\u00eda 19 de Setiembre de dos mil veintid\u00f3s a las 11:55, a petici\u00f3n de los interesados hago saber, que han proyectado unirse en matrimonio: RICARDO GUSTAVO A\u00d1\u00d3N RODRIGUEZ, c\u00e9dula de identidad 13394561 nacido\/a en Uruguay, de nacionalidad uruguaya, de 67 a\u00f1os de edad, de estado civil divorciado, de profesi\u00f3n Licenciado en Estad\u00edsiticas, domiciliado en Naciones Unidas M. 254 S. 4 El Pinar, Canelones. SILVANA PASSOS FREITAS, c\u00e9dula de identidad 54254667, nacido\/a en Brasil, de nacionalidad Brasile\u00f1a, de 45 a\u00f1os de edad, de estado civil soltera, de profesi\u00f3n Enfermera, domiciliada en Naciones Unidas M. 254 S. 4 El Pinar, Canelones. En fe de lo cual intimo a los que supieren alg\u00fan impedimento para el matrimonio proyectado denuncien por escrito ante esta Oficina haciendo conocer las causas. Y lo firmo para que sea fijado en la puerta de esta Oficina por espacio de ocho d\u00edas como lo manda la ley. Ana Maria Vera Gonzalez. Oficial de Estado Civil. 3 Pub. del 5\/12\/2022 al 7\/12\/2022 rbo. 2658<\/p>\n\n\n\n<p>LA FLORESTA<br>OFICINA N\u00ba 411<\/p>\n\n\n\n<p>En La Floresta , Canelones el d\u00eda 25 de noviembre de 2022 a las 12:49 horas, a petici\u00f3n de los interesados hago saber que han proyectado unirse en matrimonio: SILVIA RAQUEL GONZ\u00c1LEZ, c\u00e9dula de identidad 27431559 nacida en Uruguay, de nacionalidad uruguaya, de 54 a\u00f1os de edad, de estado civil soltera, de profesi\u00f3n ama de casa, domiciliada en Sierras del Mar, Cuchilla Alta, Canelones. ERNESTO EUGENIO PASIUK AUGUSTYNIAK c\u00e9dula de identidad 19302158, nacio en Uruguay, de nacionalidad uruguayo, de 54 a\u00f1os de edad, de estado civil soltero, de profesi\u00f3n empleado p\u00fablico, domiciliado en Diagonal Oeste, Sierra del Mar, Canelones. En fe de lo cual intimo a los que supieren de alg\u00fan impedimento para el matrimonio proyectado denuncien por escrito ante esta Oficina haciendo conocer las causas. Y lo firmo para que sea fijado en la puerta de esta Oficina por espacio de 8 d\u00edas como lo manda la ley. Oficial de Estado Civil . 3 pub. del 30\/11 al 2\/12\/22.<\/p>\n\n\n\n<p>PANDO<br>OFICINA N\u00ba418<\/p>\n\n\n\n<p>En PANDO, Canelones el d\u00eda 25 de Noviembre de dos mil veintid\u00f3s a las 10:30, a petici\u00f3n de los interesados hago saber, que han proyectado unirse en matrimonio: EDISON WILMAR SANCHEZ FERNANDEZ, c\u00e9dula de identidad 44625690 nacido\/a en Uruguay, de nacionalidad uruguayo, de 42 a\u00f1os de edad, de estado civil soltero, de profesi\u00f3n Mec\u00e1nico, domiciliado en Calle 1, Pando, Canelones. MARIA GABRIELA VILLAR SORIA, c\u00e9dula de identidad 40781838, nacido\/a en Uruguay, de nacionalidad uruguaya, de 37 a\u00f1os de edad, de estado civil soltera, de profesi\u00f3n Ama de casa, domiciliada en Calle 1, Pando, Canelones. En fe de lo cual intimo a los que supieren alg\u00fan impedimento para el matrimonio proyectado denuncien por escrito ante esta Oficina haciendo conocer las causas. Y lo firmo para que sea fijado en la puerta de esta Oficina por espacio de ocho d\u00edas como lo manda la ley. Documento firmado por Angela Firpo. Oficial de Estado Civil. 3 Pub. del 5\/12\/2022 al 7\/12\/2022<\/p>\n\n\n\n<p>En PANDO, Canelones el d\u00eda 1\u00ba de Diciembre de dos mil veintid\u00f3s a las 12:47, a petici\u00f3n de los interesados hago saber, que han proyectado unirse en matrimonio: NOELIA ESTEFANIA ROSAS SILVA, c\u00e9dula de identidad 44023195 nacido\/a en Uruguay, de nacionalidad uruguaya, de 31 a\u00f1os de edad, de estado civil soltera, de profesi\u00f3n Polic\u00eda, domiciliada en 8, Pando, Canelones. SEBASTIAN FEDERICO BARBIERI ACOSTA, c\u00e9dula de identidad 45934301, nacido\/a en Uruguay, de nacionalidad uruguayo, de 34 a\u00f1os de edad, de estado civil soltero, de profesi\u00f3n Trabajador independiente, domiciliada en 8, Pando, Canelones. En fe de lo cual intimo a los que supieren alg\u00fan impedimento para el matrimonio proyectado denuncien por escrito ante esta Oficina haciendo conocer las causas. Y lo firmo para que sea fijado en la puerta de esta Oficina por espacio de ocho d\u00edas como lo manda la ley. Documento firmado por Angela Firpo. Oficial de Estado Civil. 3 Pub. del 5\/12\/2022 al 7\/12\/2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JUZGADO LETRADO DE PANDO DE 4\u00ba TURNO EDICTO- Por disposici\u00f3n del Sr\/a. Juez Letrado de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-8774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edictos"],"featured_image_urls":{"full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"thumbnail":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial-150x150.jpg",150,150,true],"medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial-300x156.jpg",300,156,true],"medium_large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial-768x399.jpg",640,333,true],"large":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",640,333,false],"rpg_gallery_admin_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",150,78,false],"rpg_gallery_thumb":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",150,78,false],"1536x1536":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"2048x2048":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"covernews-slider-full":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"covernews-slider-center":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"covernews-featured":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial.jpg",800,416,false],"covernews-medium":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial-540x340.jpg",540,340,true],"covernews-medium-square":["https:\/\/diariotiempo.com.uy\/noticias\/wp-content\/uploads\/2021\/09\/judicial-400x250.jpg",400,250,true]},"author_info":{"display_name":"diario","author_link":"https:\/\/diariotiempo.com.uy\/noticias\/author\/diario\/"},"category_info":"<a href=\"https:\/\/diariotiempo.com.uy\/noticias\/category\/publicaciones\/edictos\/\" rel=\"category tag\">Edictos<\/a>","tag_info":"Edictos","comment_count":"0","_links":{"self":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/comments?post=8774"}],"version-history":[{"count":1,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8774\/revisions"}],"predecessor-version":[{"id":8775,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/posts\/8774\/revisions\/8775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media\/1819"}],"wp:attachment":[{"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/media?parent=8774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/categories?post=8774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotiempo.com.uy\/noticias\/wp-json\/wp\/v2\/tags?post=8774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}